{"id":3,"date":"2022-11-22T06:28:02","date_gmt":"2022-11-22T06:28:02","guid":{"rendered":"http:\/\/box5729\/cgi\/addon_GT.cgi?s=GT::WP::Install::EIG+%28sohoweld%29+-+10.0.87.60+%5BWordpress%3b+\/var\/hp\/common\/lib\/Wordpress.pm%3b+589%3b+Hosting::gap_call%5D\/?page_id=3"},"modified":"2024-07-03T07:23:50","modified_gmt":"2024-07-03T07:23:50","slug":"datenschutzrichtlinie","status":"publish","type":"page","link":"https:\/\/rapid-scafform.com\/de\/privacy-policy\/","title":{"rendered":"Datenschutzrichtlinie"},"content":{"rendered":"<p><strong>Wer wir sind<\/strong><\/p>\n\n\n\n<p>Unsere Website-Adresse lautet: <a href=\"http:\/\/rapid-scafform.com\/de\/\">http:\/\/rapid-scafform.com<\/a>.<\/p>\n\n\n\n<p><strong>Kommentare<\/strong><\/p>\n\n\n\n<p>Wenn Besucher Kommentare auf der Site hinterlassen, erfassen wir die im Kommentarformular angezeigten Daten sowie die IP-Adresse des Besuchers und den User-Agent-String (damit wird der Browser identifiziert), um die Spam-Erkennung zu unterst\u00fctzen.<\/p>\n\n\n\n<p>Aus Ihrer E-Mail-Adresse kann eine anonymisierte Zeichenfolge erstellt werden (auch Hash genannt) und dem Gravatar-Dienst zur Verf\u00fcgung gestellt werden, um zu pr\u00fcfen, ob Sie ihn verwenden. Die Datenschutzrichtlinie des Gravatar-Dienstes finden Sie hier: <a href=\"https:\/\/automattic.com\/privacy\/\">https:\/\/automattic.com\/privacy\/<\/a>. Nach Freigabe Ihres Kommentars ist Ihr Profilbild \u00f6ffentlich im Kontext Ihres Kommentars sichtbar.<\/p>\n\n\n\n<p><strong>Medien<\/strong><\/p>\n\n\n\n<p>Wenn Sie Bilder auf die Website hochladen, sollten Sie das Hochladen von Bildern mit eingebetteten Standortdaten (EXIF GPS) vermeiden. Besucher der Website k\u00f6nnten Standortdaten aus Bildern, die auf der Website gespeichert sind, herunterladen und extrahieren.<\/p>\n\n\n\n<p><strong>Dieses Portal verwendet Cookies zur Optimierung der Browserfunktion. Informieren Sie sich, wie wir Cookies verwenden und wie Sie Ihre Einstellungen \u00e4ndern k\u00f6nnen.<\/strong><\/p>\n\n\n\n<p>Wenn Sie einen Kommentar auf unserer Website hinterlassen, k\u00f6nnen Sie sich daf\u00fcr entscheiden, Ihren Namen, Ihre E-Mail-Adresse und Ihre Website in Cookies zu speichern. Dies dient Ihrer Bequemlichkeit, damit Sie Ihre Daten nicht erneut eingeben m\u00fcssen, wenn Sie einen weiteren Kommentar hinterlassen. Diese Cookies werden ein Jahr lang gespeichert.<\/p>\n\n\n\n<p>Wenn Sie ein Konto haben und sich auf dieser Website anmelden, werden wir ein tempor\u00e4res Cookie setzen, um festzustellen, ob Ihr Browser Cookies akzeptiert. Dieses Cookie enth\u00e4lt keine personenbezogenen Daten und wird verworfen, wenn Sie Ihren Browser schlie\u00dfen.<\/p>\n\n\n\n<p>Wenn Sie sich anmelden, werden wir au\u00dferdem mehrere Cookies einrichten, um Ihre Anmeldeinformationen und Ihre Anzeigeoptionen zu speichern. Anmelde-Cookies verfallen zwei Tage lang und Cookies f\u00fcr Anzeigeoptionen ein Jahr lang. Wenn Sie \u201eAngemeldet bleiben\u201c ausw\u00e4hlen, bleibt Ihre Anmeldung zwei Wochen lang bestehen. Wenn Sie sich von Ihrem Konto abmelden, werden die Anmelde-Cookies gel\u00f6scht.<\/p>\n\n\n\n<p>Wenn Sie einen Artikel bearbeiten oder ver\u00f6ffentlichen, wird ein zus\u00e4tzlicher Cookie in Ihrem Browser gespeichert. Dieser Cookie enth\u00e4lt keine personenbezogenen Daten und gibt lediglich die Beitrags-ID des Artikels an, den Sie gerade bearbeitet haben. Er verf\u00e4llt nach einem Tag.<\/p>\n\n\n\n<p><strong>Eingebettete Inhalte von anderen Websites<\/strong><\/p>\n\n\n\n<p>Beitr\u00e4ge auf dieser Website k\u00f6nnen eingebettete Inhalte beinhalten (z. B. Videos, Bilder, Beitr\u00e4ge etc.). Eingebettete Inhalte von anderen Websites verhalten sich exakt so, als ob der Besucher die andere Website besucht h\u00e4tte.<\/p>\n\n\n\n<p>Diese Websites k\u00f6nnen Daten \u00fcber Sie sammeln, Cookies benutzen, zus\u00e4tzliche Tracking-Dienste von Dritten einbetten und Ihre Interaktion mit diesem eingebetteten Inhalt aufzeichnen, inklusive Ihrer Interaktion mit dem eingebetteten Inhalt, falls Sie ein Konto haben und auf dieser Website angemeldet sind.<\/p>\n\n\n\n<p><strong>Mit wem wir Ihre Daten teilen<\/strong><\/p>\n\n\n\n<p>Wenn Sie eine Zur\u00fccksetzung des Passworts anfordern, wird Ihre IP-Adresse in der E-Mail zur Zur\u00fccksetzung enthalten sein.<\/p>\n\n\n\n<p><strong>Wie lange wir Ihre Daten speichern<\/strong><\/p>\n\n\n\n<p>Wenn Sie einen Kommentar hinterlassen, werden dieser und seine Metadaten zeitlich unbegrenzt gespeichert. Auf diese Weise k\u00f6nnen wir Folgekommentare automatisch erkennen und freigeben, anstatt sie in einer Moderationswarteschlange festzuhalten.<\/p>\n\n\n\n<p>F\u00fcr Benutzer, die sich auf unserer Website registrieren (falls vorhanden), speichern wir zus\u00e4tzlich die pers\u00f6nlichen Informationen, die sie in ihren Benutzerprofilen angeben. Alle Benutzer k\u00f6nnen ihre pers\u00f6nlichen Informationen jederzeit einsehen, bearbeiten oder l\u00f6schen (der Benutzername kann nicht ge\u00e4ndert werden). Website-Administratoren k\u00f6nnen diese Informationen ebenfalls einsehen und bearbeiten.<\/p>\n\n\n\n<p><strong>Welche Rechte Sie an Ihren Daten haben<\/strong><\/p>\n\n\n\n<p>Wenn Sie ein Konto auf dieser Site besitzen oder Kommentare geschrieben haben, k\u00f6nnen Sie einen Export Ihrer bei uns gespeicherten personenbezogenen Daten anfordern, inklusive aller Daten, die Sie uns mitgeteilt haben. Dar\u00fcber hinaus k\u00f6nnen Sie die L\u00f6schung aller von Ihnen gespeicherten personenbezogenen Daten anfordern. Dies umfasst nicht die Daten, die wir aufgrund administrativer, rechtlicher oder sicherheitsrelevanter Notwendigkeiten aufbewahren m\u00fcssen.<\/p>\n\n\n\n<p><strong>Wohin Ihre Daten gesendet werden<\/strong><\/p>\n\n\n\n<p>Besucherkommentare k\u00f6nnten von einem automatisierten Dienst zur Spam-Erkennung untersucht werden.<\/p>\n\n\n\n<p><strong>Kontaktinformationen<\/strong><\/p>\n\n\n\n<p>Wenn Sie Fragen zu dieser Datenschutzrichtlinie haben, kontaktieren Sie uns bitte unter <a>info@rapid-scafform.com<\/a>.<\/p>\n\n\n\n<p><strong>\u00c4nderungen dieser Datenschutzrichtlinie<\/strong><\/p>\n\n\n\n<p>Wir k\u00f6nnen unsere Datenschutzrichtlinie von Zeit zu Zeit aktualisieren. Wir werden Sie \u00fcber alle \u00c4nderungen informieren, indem wir die neue Datenschutzrichtlinie auf dieser Seite ver\u00f6ffentlichen. Wir empfehlen Ihnen, diese Datenschutzrichtlinie regelm\u00e4\u00dfig auf \u00c4nderungen zu \u00fcberpr\u00fcfen. \u00c4nderungen an dieser Datenschutzrichtlinie werden wirksam, wenn sie auf dieser Seite ver\u00f6ffentlicht werden.<\/p>\n\n\n\n<p><strong>Weitere Informationen<\/strong><\/p>\n\n\n\n<p><strong>So sch\u00fctzen wir Ihre Daten<\/strong><\/p>\n\n\n\n<p>Wir implementieren eine Reihe von Sicherheitsma\u00dfnahmen, um die Sicherheit Ihrer pers\u00f6nlichen Daten zu gew\u00e4hrleisten, wenn Sie Ihre pers\u00f6nlichen Daten eingeben, \u00fcbermitteln oder darauf zugreifen.<\/p>\n\n\n\n<p><strong>Welche Verfahren wir bei Datenschutzverletzungen anwenden<\/strong><\/p>\n\n\n\n<p>Im Falle einer Datenpanne benachrichtigen wir die betroffenen Benutzer innerhalb von 72 Stunden, nachdem wir von der Panne erfahren haben. Wir haben Datenschutzbeauftragte und interne Richtlinien, um solche Vorf\u00e4lle effektiv zu handhaben.<\/p>\n\n\n\n<p><strong>Von welchen Drittanbietern wir Daten erhalten<\/strong><\/p>\n\n\n\n<p>Wir erhalten unter Umst\u00e4nden Daten \u00fcber Sie von Dritten, insbesondere von Partnern und Dienstanbietern.<\/p>\n\n\n\n<p><strong>Welche automatisierte Entscheidungsfindung und\/oder Profilerstellung wir mit Benutzerdaten durchf\u00fchren<\/strong><\/p>\n\n\n\n<p>Eine automatisierte Entscheidungsfindung oder Profilerstellung mit Nutzerdaten findet bei uns nicht statt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Who We Are Our website address is: http:\/\/rapid-scafform.com. Comments When visitors leave comments on the site, we collect the data shown in the comments form, as well as the visitor\u2019s IP address and browser user agent string to help with spam detection. An anonymized string created from your email address (also called a hash) may [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rapid-scafform.com\/de\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rapid-scafform.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rapid-scafform.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rapid-scafform.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rapid-scafform.com\/de\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":1,"href":"https:\/\/rapid-scafform.com\/de\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":6924,"href":"https:\/\/rapid-scafform.com\/de\/wp-json\/wp\/v2\/pages\/3\/revisions\/6924"}],"wp:attachment":[{"href":"https:\/\/rapid-scafform.com\/de\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}