{"id":8284,"date":"2024-11-06T01:30:15","date_gmt":"2024-11-06T01:30:15","guid":{"rendered":"https:\/\/rapid-scafform.com\/?p=8284"},"modified":"2024-11-06T01:30:19","modified_gmt":"2024-11-06T01:30:19","slug":"echafaudage-ringlock-de-la-centrale-de-pompage-turbinage-de-jiangsu-liyang","status":"publish","type":"post","link":"https:\/\/rapid-scafform.com\/fr\/ringlock-scaffolding-jiangsu-liyang-pumped-storage-power-station\/","title":{"rendered":"\u00c9chafaudage Ringlock \u00e0 la centrale de pompage-turbinage de Jiangsu Liyang"},"content":{"rendered":"<p>Le 22 octobre 2024, le <strong>Conf\u00e9rence acad\u00e9mique annuelle de la Soci\u00e9t\u00e9 chinoise de g\u00e9nie civil<\/strong>\u00a0et le <strong>20e c\u00e9r\u00e9monie de remise du prix Zhan Tianyou du g\u00e9nie civil chinois<\/strong>\u00a0ont eu lieu \u00e0 Suzhou. <strong>Centrale \u00e9lectrique de stockage par pompage de Jiangsu Liyang<\/strong>, un projet important dans le secteur hydro\u00e9lectrique chinois, a remport\u00e9 le prestigieux <strong>Prix Zhan Tianyou<\/strong>, une distinction nationale pour l&#039;innovation technologique dans le g\u00e9nie civil. Rapid Scaffolding (Engineering) Co., Ltd. \u00e9tait fi\u00e8re de contribuer au succ\u00e8s de ce projet historique, en employant <strong><a href=\"https:\/\/rapid-scafform.com\/fr\/ringlock-echafaudage\/\" data-type=\"page\" data-id=\"5450\">Syst\u00e8mes d&#039;\u00e9chafaudages Ringlock<\/a><\/strong>\u00a0pour sa construction.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"646\" height=\"431\" src=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image.webp\" alt=\"image\" class=\"wp-image-8287\" style=\"width:639px;height:auto\" srcset=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image.webp 646w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-300x200.webp 300w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-18x12.webp 18w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-600x400.webp 600w\" sizes=\"(max-width: 646px) 100vw, 646px\" \/><\/figure>\n\n\n\n<p>Cet article explore comment <strong><a href=\"https:\/\/rapid-scafform.com\/fr\/faq-sur-lechafaudage-rapide\/\" data-type=\"page\" data-id=\"7513\">\u00c9chafaudage Ringlock<\/a><\/strong>, ainsi que d&#039;autres innovations techniques, ont jou\u00e9 un r\u00f4le crucial pour surmonter les d\u00e9fis uniques pr\u00e9sent\u00e9s lors de la construction de cette centrale de pompage-turbinage. Cela souligne \u00e9galement l&#039;impact plus large du projet et l&#039;importance de <a href=\"https:\/\/rapid-scafform.com\/fr\/produit-2\/\" data-type=\"page\" data-id=\"5349\"><strong>syst\u00e8mes d&#039;\u00e9chafaudage<\/strong>\u00a0<\/a>dans des projets d\u2019infrastructures \u00e0 grande \u00e9chelle en Chine.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"639\" height=\"383\" src=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-1.webp\" alt=\"image\" class=\"wp-image-8288\" srcset=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-1.webp 639w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-1-300x180.webp 300w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-1-18x12.webp 18w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-1-600x360.webp 600w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le r\u00f4le des \u00e9chafaudages Ringlock dans les projets hydro\u00e9lectriques \u00e0 grande \u00e9chelle<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>Le <strong>Centrale \u00e9lectrique de stockage par pompage de Jiangsu Liyang<\/strong>\u00a0est la plus grande de la province du Jiangsu et la quatri\u00e8me plus grande de Chine. Ce projet de grande envergure comprend des \u00e9l\u00e9ments cl\u00e9s tels que le r\u00e9servoir sup\u00e9rieur, le syst\u00e8me de transmission d&#039;eau, la centrale \u00e9lectrique souterraine et le r\u00e9servoir inf\u00e9rieur. Chaque partie de la station posait des d\u00e9fis de construction uniques, et l&#039;utilisation d&#039;\u00e9chafaudages Ringlock \u00e9tait essentielle pour fournir un syst\u00e8me de support fiable et efficace.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"652\" height=\"420\" src=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-2.webp\" alt=\"image\" class=\"wp-image-8289\" srcset=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-2.webp 652w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-2-300x193.webp 300w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-2-18x12.webp 18w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-2-600x387.webp 600w\" sizes=\"(max-width: 652px) 100vw, 652px\" \/><\/figure>\n\n\n\n<p>La partie la plus complexe de la construction \u00e9tait la <strong>c\u00f4ne de redressement<\/strong>\u00a0avec une plaque de recouvrement, suspendue directement au-dessus de l&#039;arriv\u00e9e d&#039;eau. Cette partie n\u00e9cessitait un \u00e9chafaudage capable de supporter de grandes port\u00e9es et de lourdes charges. Le syst\u00e8me d&#039;\u00e9chafaudage Ringlock a fourni le support n\u00e9cessaire en raison de son adaptabilit\u00e9, de sa r\u00e9sistance et de sa facilit\u00e9 d&#039;installation, ce qui a \u00e9t\u00e9 crucial pour le succ\u00e8s de ce composant.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"654\" height=\"394\" src=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-3.webp\" alt=\"image\" class=\"wp-image-8290\" srcset=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-3.webp 654w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-3-300x181.webp 300w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-3-18x12.webp 18w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-3-600x361.webp 600w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"671\" height=\"255\" src=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-4.webp\" alt=\"image\" class=\"wp-image-8291\" style=\"width:651px;height:auto\" srcset=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-4.webp 671w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-4-300x114.webp 300w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-4-18x7.webp 18w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-4-600x228.webp 600w\" sizes=\"(max-width: 671px) 100vw, 671px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Avantages des \u00e9chafaudages Ringlock pour les projets hydro\u00e9lectriques<\/strong><strong><\/strong><\/h3>\n\n\n\n<p><strong><a href=\"https:\/\/rapid-scafform.com\/fr\/guide-essentiel-de-lechafaudage-systeme\/\" data-type=\"post\" data-id=\"8217\">\u00c9chafaudage Ringlock<\/a><\/strong>\u00a0est largement utilis\u00e9 dans les \u00e9chafaudages en Chine en raison de sa polyvalence et de sa capacit\u00e9 \u00e0 r\u00e9pondre \u00e0 des exigences de construction complexes. Le syst\u00e8me d&#039;\u00e9chafaudage Ringlock est particuli\u00e8rement adapt\u00e9 \u00e0 des projets tels que la centrale de pompage-turbinage de Jiangsu Liyang en raison des avantages suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Flexibilit\u00e9 dans la conception<\/strong>:La nature modulaire de l&#039;\u00e9chafaudage Ringlock permet une personnalisation facile, ce qui le rend id\u00e9al pour les structures grandes et complexes telles que le c\u00f4ne de rectification.<\/li>\n\n\n\n<li><strong>Capacit\u00e9 de charge \u00e9lev\u00e9e<\/strong>:Les \u00e9chafaudages Ringlock peuvent supporter un poids important, ce qui est essentiel lorsque l&#039;on travaille avec des composants massifs tels que les structures d&#039;arriv\u00e9e d&#039;eau.<\/li>\n\n\n\n<li><strong>Facilit\u00e9 d&#039;installation<\/strong>:Gr\u00e2ce \u00e0 sa conception d&#039;embo\u00eetement efficace, l&#039;\u00e9chafaudage Ringlock r\u00e9duit consid\u00e9rablement le temps d&#039;installation, garantissant que les \u00e9quipes de construction peuvent se concentrer sur d&#039;autres aspects critiques du projet.<\/li>\n\n\n\n<li><strong>S\u00e9curit\u00e9<\/strong>:Le syst\u00e8me d&#039;\u00e9chafaudage Ringlock am\u00e9liore la s\u00e9curit\u00e9 des travailleurs, en fournissant une plate-forme stable pour les activit\u00e9s de construction \u00e0 haute altitude, comme les tours de 53 m\u00e8tres de haut du r\u00e9servoir sup\u00e9rieur de la station de Liyang.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Solutions d&#039;\u00e9chafaudage pour la centrale de pompage-turbinage de Jiangsu Liyang<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>Pendant la construction de la <strong>Centrale \u00e9lectrique de stockage par pompage de Jiangsu Liyang<\/strong>, le projet n\u00e9cessitait une combinaison de <strong>plates-formes suspendues en acier<\/strong>\u00a0et <strong>\u00c9chafaudage Ringlock<\/strong>\u00a0pour former le cadre de support. \u00c0 la base en b\u00e9ton de la station \u00e0 <strong>altitude 238,2 m\u00e8tres<\/strong>, une structure en b\u00e9ton de 2,2 m\u00e8tres de large a \u00e9t\u00e9 r\u00e9serv\u00e9e pour un coulage ult\u00e9rieur. <strong>poutre en acier \u00e0 section variable<\/strong>, 21 m\u00e8tres de large, a \u00e9t\u00e9 soud\u00e9 et fabriqu\u00e9, et suspendu \u00e0 l&#039;aide <strong>Brins d&#039;acier \u03a615,24<\/strong>Cette m\u00e9thode de construction innovante a \u00e9t\u00e9 rendue possible gr\u00e2ce \u00e0 l\u2019adaptabilit\u00e9 et \u00e0 la r\u00e9sistance des \u00e9chafaudages Ringlock.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"479\" src=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-5.webp\" alt=\"image\" class=\"wp-image-8292\" srcset=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-5.webp 580w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-5-300x248.webp 300w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-5-15x12.webp 15w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/figure>\n\n\n\n<p>De plus, le projet a utilis\u00e9 une approche de tension progressive et de moulage multicouche pour le <strong>c\u00f4ne de redressement<\/strong>, soulignant davantage le r\u00f4le essentiel que jouent les \u00e9chafaudages dans la r\u00e9duction de la charge de travail et de la complexit\u00e9 des projets de construction \u00e0 grande \u00e9chelle.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"565\" height=\"716\" src=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-6.webp\" alt=\"image\" class=\"wp-image-8293\" srcset=\"https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-6.webp 565w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-6-237x300.webp 237w, https:\/\/rapid-scafform.com\/wp-content\/uploads\/2024\/11\/image-6-9x12.webp 9w\" sizes=\"(max-width: 565px) 100vw, 565px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c9chafaudages Ringlock : un contributeur cl\u00e9 \u00e0 l&#039;innovation technologique dans le g\u00e9nie civil en Chine<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>Le <strong>Prix Zhan Tianyou<\/strong>\u00a0est la plus haute distinction chinoise pour l&#039;innovation en mati\u00e8re de g\u00e9nie civil, et <strong>Centrale \u00e9lectrique de stockage par pompage de Jiangsu Liyang<\/strong>\u00a0Le projet s&#039;est distingu\u00e9 par son excellence technologique. La collaboration entre <strong>\u00c9chafaudage rapide (ing\u00e9nierie) Co., Ltd.<\/strong>\u00a0et <strong>Universit\u00e9 du Sud-Est<\/strong>\u00a0La construction du corps de la tour de type puits pour les huit vannes d&#039;\u00e9cluse de maintenance montre comment l&#039;\u00e9chafaudage Ringlock peut contribuer au succ\u00e8s des projets cl\u00e9s nationaux en Chine.<\/p>\n\n\n\n<p>Cette reconnaissance souligne l\u2019importance d\u2019adopter des solutions d\u2019\u00e9chafaudage avanc\u00e9es pour r\u00e9pondre aux exigences exigeantes des projets d\u2019infrastructures modernes, en particulier ceux du secteur hydro\u00e9lectrique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Perspectives d&#039;avenir : faire progresser la construction gr\u00e2ce aux \u00e9chafaudages en Chine<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>Le succ\u00e8s de la <strong>Centrale \u00e9lectrique de stockage par pompage de Jiangsu Liyang<\/strong>\u00a0n&#039;est pas seulement un t\u00e9moignage de l&#039;utilisation innovante des \u00e9chafaudages Ringlock, mais aussi un exemple de la fa\u00e7on dont les \u00e9chafaudages en Chine ont \u00e9volu\u00e9 pour r\u00e9pondre aux exigences des projets de construction complexes \u00e0 grande \u00e9chelle. <strong>\u00c9chafaudage rapide (ing\u00e9nierie) Co., Ltd.<\/strong>\u00a0continuera \u00e0 se concentrer sur <strong>innovation technologique<\/strong>\u00a0et <strong>am\u00e9lioration de la qualit\u00e9<\/strong>\u00a0dans les syst\u00e8mes d&#039;\u00e9chafaudage, garantissant que l&#039;\u00e9chafaudage Ringlock reste un \u00e9l\u00e9ment cl\u00e9 dans la construction de futures centrales hydro\u00e9lectriques, d&#039;installations industrielles et de projets d&#039;infrastructure \u00e0 travers la Chine.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conclusion<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>Le <strong>Centrale \u00e9lectrique de stockage par pompage de Jiangsu Liyang<\/strong>&nbsp;est une r\u00e9alisation monumentale dans le paysage du g\u00e9nie civil chinois, et le succ\u00e8s de ce projet a \u00e9t\u00e9 rendu possible par l&#039;utilisation de techniques de construction avanc\u00e9es, notamment <strong>Syst\u00e8me d&#039;\u00e9chafaudage Ringlock<\/strong>En tant que plus grande centrale de pompage-turbinage de la province du Jiangsu et la quatri\u00e8me plus grande de Chine, ce projet illustre le r\u00f4le essentiel que jouent les syst\u00e8mes d&#039;\u00e9chafaudage dans <strong>projets d&#039;infrastructures \u00e0 grande \u00e9chelle<\/strong>. En continuant \u00e0 innover et \u00e0 optimiser <strong>solutions d&#039;\u00e9chafaudage<\/strong>, des entreprises comme <strong>\u00c9chafaudage rapide (ing\u00e9nierie) Co., Ltd.<\/strong>&nbsp;contribuent \u00e0 fa\u00e7onner l&#039;avenir de <strong>Ing\u00e9nierie civile en Chine<\/strong>.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>On October 22, 2024, the Academic Annual Conference of the China Civil Engineering Society\u00a0and the 20th China Civil Engineering Zhan Tianyou Award Ceremony\u00a0were held in Suzhou. The Jiangsu Liyang Pumped Storage Power Station, a significant project in China\u2019s hydropower sector, won the prestigious Zhan Tianyou Award, a national honour for technological innovation in civil engineering. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8289,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Ringlock Scaffolding at Jiangsu Liyang Pumped Storage Power Station","_seopress_titles_desc":"Explore how Ringlock scaffolding played a critical role in the construction of the Jiangsu Liyang Pumped Storage Power Station, one of China\u2019s largest hydropower projects. Learn about its applications, benefits, and contributions to the project's success.","_seopress_robots_index":"","_seopress_analysis_target_kw":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[44],"tags":[],"class_list":["post-8284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-project"],"_links":{"self":[{"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/posts\/8284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/comments?post=8284"}],"version-history":[{"count":1,"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/posts\/8284\/revisions"}],"predecessor-version":[{"id":8294,"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/posts\/8284\/revisions\/8294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/media\/8289"}],"wp:attachment":[{"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/media?parent=8284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/categories?post=8284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rapid-scafform.com\/fr\/wp-json\/wp\/v2\/tags?post=8284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}